{"id":17953,"date":"2020-03-20T13:15:03","date_gmt":"2020-03-20T12:15:03","guid":{"rendered":"https:\/\/grupobcc.com\/novedades-it\/alessandro-baricco-esto-nos-va-a-lanzar-al-futuro-definitivamente\/"},"modified":"2020-04-13T09:59:16","modified_gmt":"2020-04-13T07:59:16","slug":"alessandro-baricco-esto-nos-va-a-lanzar-al-futuro-definitivamente","status":"publish","type":"post","link":"https:\/\/grupobcc.com\/it\/novedades-it\/alessandro-baricco-esto-nos-va-a-lanzar-al-futuro-definitivamente\/","title":{"rendered":"Alessandro Baricco: \u201cEsto nos va a lanzar al futuro definitivamente\u201d"},"content":{"rendered":"<h4><img loading=\"lazy\" width=\"940\" height=\"660\" class=\"alignnone size-full wp-image-17947\" src=\"https:\/\/grupobcc.com\/wp\/wp-content\/uploads\/2020\/04\/Alessandro-Baricco-speaker-scritore-keynote-speech-e1467978010165.jpg\" alt=\"Alessandro Baricco\" srcset=\"https:\/\/grupobcc.com\/wp\/wp-content\/uploads\/2020\/04\/Alessandro-Baricco-speaker-scritore-keynote-speech-e1467978010165.jpg 940w, https:\/\/grupobcc.com\/wp\/wp-content\/uploads\/2020\/04\/Alessandro-Baricco-speaker-scritore-keynote-speech-e1467978010165-300x211.jpg 300w, https:\/\/grupobcc.com\/wp\/wp-content\/uploads\/2020\/04\/Alessandro-Baricco-speaker-scritore-keynote-speech-e1467978010165-768x539.jpg 768w, https:\/\/grupobcc.com\/wp\/wp-content\/uploads\/2020\/04\/Alessandro-Baricco-speaker-scritore-keynote-speech-e1467978010165-541x380.jpg 541w\" sizes=\"(max-width: 940px) 100vw, 940px\" \/><\/h4>\n<h4><\/h4>\n<h4>Compartimos un fragmento del art\u00edculo publicado por &#8216;El Pa\u00eds&#8217; en el que nuestro speaker <a href=\"https:\/\/grupobcc.com\/it\/speakers\/alessandro-baricco\/\"><strong><span style=\"color: #ff6600;\">Alessandro Baricco<\/span> <\/strong><\/a>comparte su visi\u00f3n sobre la situaci\u00f3n que estamos viviendo y hacia d\u00f3nde nos va a llevar:<\/h4>\n<p class=\"lead\">&nbsp;<\/p>\n<h4>\u201cHemos tenido un accidente de coche. Un accidente de coche mundial. Los implicados somos todos. Todav\u00eda estamos tratando de sacar a los muertos y los heridos del amasijo de hierro en que ha quedado convertido el monstruoso veh\u00edculo en el que viaj\u00e1bamos. Luego empezaremos a preguntarnos c\u00f3mo fue que pas\u00f3, si pudimos evitarlo, si habr\u00e1 una pr\u00f3xima vez.\u201d As\u00ed define Alessandro Baricco (62 a\u00f1os) escritor y pensador de \u201cla superficie\u201d, c\u00f3mo \u00e9l se define, autor del premonitorio Game (Anagrama), el impacto del coronavirus en el mundo. \u201cLa democracia en este momento funciona como sistema de emergencia\u201d, dice a continuaci\u00f3n. Es la ambulancia que acude a nuestro rescate. \u201cDe ah\u00ed la confianza que, de repente, le tenemos. Venimos de a\u00f1os de crisis profunda de confianza con la clase pol\u00edtica y cient\u00edfica, y en una semana es lo \u00fanico que tenemos. Parece que solo somos capaces de vivir juntos cuando se nos obliga a ser disciplinados. Y esto est\u00e1 siendo solo un ensayo general.<\/h4>\n<h4><\/h4>\n<h4>Pasaremos los pr\u00f3ximos 50 a\u00f1os as\u00ed. El planeta se est\u00e1 acabando\u201d, dispara Baricco.<\/h4>\n<p>&nbsp;<\/p>\n<h4>El escritor est\u00e1 confinado en su casa de Tur\u00edn. Lo que el espectador ve es su cara en la pantalla de cualquiera sea el dispositivo desde el que acceda a la web del Centro de Cultura Contempor\u00e1nea de Barcelona. Sale cada d\u00eda a comprar, hace la cola en el supermercado y regresa a casa, donde le esperan sus hijos. Es complicado trabajar con sus hijos en casa, dice, en un ejercicio de empat\u00eda mundial. El cuadro que hay a su espalda es una ic\u00f3nica imagen de Nueva York \u201cen la \u00e9poca en que a\u00fan se fletaban barcos de vela\u201d. A su lado, en la pantalla dividida, puede verse parte de la biblioteca del escritor y tambi\u00e9n pensador Jorge Carri\u00f3n, encargado de presentar la charla Humanidad Aumentada, que iba a tener lugar en Barcelona la tarde del lunes 16 de marzo. Est\u00e1 teniendo lugar de todas formas. Hay 375 personas conectadas, vi\u00e9ndoles. \u201cEs un contexto hist\u00f3rico, terrible y, no obstante, fascinante\u201d, dice Carri\u00f3n. Baricco le secunda. \u201cPara la mente del intelectual, lo que est\u00e1 ocurriendo, pese a la pena, es una fiesta porque todo lo que ves est\u00e1 cambiando el mundo. El pensador est\u00e1 viviendo un momento m\u00e1gico\u201d, a\u00f1ade. (&#8230;)<\/h4>\n<p>&nbsp;<\/p>\n<h4>Te invitamos a leer el art\u00edculo completo en el siguiente enlace: <a href=\"https:\/\/elpais.com\/cultura\/2020-03-17\/alessandro-baricco-esto-nos-va-a-lanzar-al-futuro-definitivamente.html\">https:\/\/elpais.com\/cultura\/2020-03-17\/alessandro-baricco-esto-nos-va-a-lanzar-al-futuro-definitivamente.html<\/a><\/h4>\n","protected":false},"excerpt":{"rendered":"<p>Compartimos un fragmento del art\u00edculo publicado por &#8216;El Pa\u00eds&#8217; en el que nuestro speaker Alessandro Baricco comparte su visi\u00f3n sobre la situaci\u00f3n que estamos viviendo y hacia d\u00f3nde nos va a llevar: &nbsp; \u201cHemos tenido un accidente de coche. Un accidente de coche mundial. Los implicados somos todos. Todav\u00eda estamos tratando de sacar a los&#8230;  <a href=\"https:\/\/grupobcc.com\/it\/novedades-it\/alessandro-baricco-esto-nos-va-a-lanzar-al-futuro-definitivamente\/\" class=\"more-link\" title=\"Read Alessandro Baricco: \u201cEsto nos va a lanzar al futuro definitivamente\u201d\">Read more &raquo;<\/a><\/p>\n","protected":false},"author":12,"featured_media":17950,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[107],"tags":[600,601,602],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"description\" content=\"Parece que solo somos capaces de vivir juntos cuando se nos obliga a ser disciplinados. Y esto est\u00e1 siendo solo un ensayo general.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/grupobcc.com\/it\/novedades-it\/alessandro-baricco-esto-nos-va-a-lanzar-al-futuro-definitivamente\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alessandro Baricco: \u201cEsto nos va a lanzar al futuro definitivamente\u201d\" \/>\n<meta property=\"og:description\" content=\"Parece que solo somos capaces de vivir juntos cuando se nos obliga a ser disciplinados. Y esto est\u00e1 siendo solo un ensayo general.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/grupobcc.com\/it\/novedades-it\/alessandro-baricco-esto-nos-va-a-lanzar-al-futuro-definitivamente\/\" \/>\n<meta property=\"og:site_name\" content=\"BCC Speakers\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-20T12:15:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-13T07:59:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/grupobcc.com\/wp\/wp-content\/uploads\/2020\/04\/Alessandro-Baricco-speaker-scritore-keynote-speech-e1467978010165.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"660\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:creator\" content=\"@BCCSpeakers\" \/>\n<meta name=\"twitter:site\" content=\"@BCCSpeakers\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/grupobcc.com\/it\/#website\",\"url\":\"https:\/\/grupobcc.com\/it\/\",\"name\":\"BCC Speakers\",\"description\":\"The International Speakers Bureau\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/grupobcc.com\/it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/grupobcc.com\/it\/novedades-it\/alessandro-baricco-esto-nos-va-a-lanzar-al-futuro-definitivamente\/#primaryimage\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/grupobcc.com\/wp\/wp-content\/uploads\/2020\/04\/Alessandro-Baricco-speaker-scritore-keynote-speech-e1467978010165.jpg\",\"contentUrl\":\"https:\/\/grupobcc.com\/wp\/wp-content\/uploads\/2020\/04\/Alessandro-Baricco-speaker-scritore-keynote-speech-e1467978010165.jpg\",\"width\":940,\"height\":660,\"caption\":\"Alessandro Baricco\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/grupobcc.com\/it\/novedades-it\/alessandro-baricco-esto-nos-va-a-lanzar-al-futuro-definitivamente\/#webpage\",\"url\":\"https:\/\/grupobcc.com\/it\/novedades-it\/alessandro-baricco-esto-nos-va-a-lanzar-al-futuro-definitivamente\/\",\"name\":\"Alessandro Baricco: \\u201cEsto nos va a lanzar al futuro definitivamente\\u201d\",\"isPartOf\":{\"@id\":\"https:\/\/grupobcc.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/grupobcc.com\/it\/novedades-it\/alessandro-baricco-esto-nos-va-a-lanzar-al-futuro-definitivamente\/#primaryimage\"},\"datePublished\":\"2020-03-20T12:15:03+00:00\",\"dateModified\":\"2020-04-13T07:59:16+00:00\",\"author\":{\"@id\":\"https:\/\/grupobcc.com\/it\/#\/schema\/person\/db745cb18f6eca108cd3b0c07d9ce915\"},\"description\":\"Parece que solo somos capaces de vivir juntos cuando se nos obliga a ser disciplinados. Y esto est\\u00e1 siendo solo un ensayo general.\",\"breadcrumb\":{\"@id\":\"https:\/\/grupobcc.com\/it\/novedades-it\/alessandro-baricco-esto-nos-va-a-lanzar-al-futuro-definitivamente\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/grupobcc.com\/it\/novedades-it\/alessandro-baricco-esto-nos-va-a-lanzar-al-futuro-definitivamente\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/grupobcc.com\/it\/novedades-it\/alessandro-baricco-esto-nos-va-a-lanzar-al-futuro-definitivamente\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/grupobcc.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alessandro Baricco: \\u201cEsto nos va a lanzar al futuro definitivamente\\u201d\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/grupobcc.com\/it\/#\/schema\/person\/db745cb18f6eca108cd3b0c07d9ce915\",\"name\":\"Laura\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/grupobcc.com\/it\/#personlogo\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a6d31b10824aca1fac2be3d9ca83fb29?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a6d31b10824aca1fac2be3d9ca83fb29?s=96&d=mm&r=g\",\"caption\":\"Laura\"},\"url\":\"https:\/\/grupobcc.com\/it\/author\/laura\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/grupobcc.com\/it\/wp-json\/wp\/v2\/posts\/17953"}],"collection":[{"href":"https:\/\/grupobcc.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grupobcc.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/grupobcc.com\/it\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/grupobcc.com\/it\/wp-json\/wp\/v2\/comments?post=17953"}],"version-history":[{"count":2,"href":"https:\/\/grupobcc.com\/it\/wp-json\/wp\/v2\/posts\/17953\/revisions"}],"predecessor-version":[{"id":17967,"href":"https:\/\/grupobcc.com\/it\/wp-json\/wp\/v2\/posts\/17953\/revisions\/17967"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grupobcc.com\/it\/wp-json\/wp\/v2\/media\/17950"}],"wp:attachment":[{"href":"https:\/\/grupobcc.com\/it\/wp-json\/wp\/v2\/media?parent=17953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grupobcc.com\/it\/wp-json\/wp\/v2\/categories?post=17953"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grupobcc.com\/it\/wp-json\/wp\/v2\/tags?post=17953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}